{"id":88,"count":133,"description":"","link":"https:\/\/pfc.parts\/webcat\/product-category\/caliper-hardware-spares-gloves\/","name":"Caliper hardware, spares + gloves","slug":"caliper-hardware-spares-gloves","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caliper hardware, spares + gloves Archives - PFC Brakes applications<\/title>\n<meta name=\"description\" content=\"PFC Brakes applications Caliper hardware, spares + gloves Caliper hardware, spares + gloves %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pfc.parts\/webcat\/product-category\/caliper-hardware-spares-gloves\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caliper hardware, spares + gloves Archives - PFC Brakes applications\" \/>\n<meta property=\"og:description\" content=\"PFC Brakes applications Caliper hardware, spares + gloves Caliper hardware, spares + gloves %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pfc.parts\/webcat\/product-category\/caliper-hardware-spares-gloves\/\" \/>\n<meta property=\"og:site_name\" content=\"PFC Brakes applications\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PFCbrakes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/product-category\\\/caliper-hardware-spares-gloves\\\/\",\"url\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/product-category\\\/caliper-hardware-spares-gloves\\\/\",\"name\":\"Caliper hardware, spares + gloves Archives - PFC Brakes applications\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/#website\"},\"description\":\"PFC Brakes applications Caliper hardware, spares + gloves Caliper hardware, spares + gloves %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/product-category\\\/caliper-hardware-spares-gloves\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/product-category\\\/caliper-hardware-spares-gloves\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caliper hardware, spares + gloves\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/#website\",\"url\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/\",\"name\":\"PFC Brakes applications\",\"description\":\"PFC Brakes - Performance Friction\",\"publisher\":{\"@id\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/#organization\",\"name\":\"PFC Brakes\",\"url\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/BMW-RACE-DISC-CALIPER-sm.png\",\"contentUrl\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/BMW-RACE-DISC-CALIPER-sm.png\",\"width\":400,\"height\":327,\"caption\":\"PFC Brakes\"},\"image\":{\"@id\":\"https:\\\/\\\/pfc.parts\\\/webcat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PFCBrakes\",\"https:\\\/\\\/x.com\\\/PFCbrakes\",\"https:\\\/\\\/www.instagram.com\\\/pfcbrakes\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caliper hardware, spares + gloves Archives - PFC Brakes applications","description":"PFC Brakes applications Caliper hardware, spares + gloves Caliper hardware, spares + gloves %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pfc.parts\/webcat\/product-category\/caliper-hardware-spares-gloves\/","og_locale":"en_US","og_type":"article","og_title":"Caliper hardware, spares + gloves Archives - PFC Brakes applications","og_description":"PFC Brakes applications Caliper hardware, spares + gloves Caliper hardware, spares + gloves %","og_url":"https:\/\/pfc.parts\/webcat\/product-category\/caliper-hardware-spares-gloves\/","og_site_name":"PFC Brakes applications","twitter_card":"summary_large_image","twitter_site":"@PFCbrakes","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/pfc.parts\/webcat\/product-category\/caliper-hardware-spares-gloves\/","url":"https:\/\/pfc.parts\/webcat\/product-category\/caliper-hardware-spares-gloves\/","name":"Caliper hardware, spares + gloves Archives - PFC Brakes applications","isPartOf":{"@id":"https:\/\/pfc.parts\/webcat\/#website"},"description":"PFC Brakes applications Caliper hardware, spares + gloves Caliper hardware, spares + gloves %","breadcrumb":{"@id":"https:\/\/pfc.parts\/webcat\/product-category\/caliper-hardware-spares-gloves\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/pfc.parts\/webcat\/product-category\/caliper-hardware-spares-gloves\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pfc.parts\/webcat\/"},{"@type":"ListItem","position":2,"name":"Caliper hardware, spares + gloves"}]},{"@type":"WebSite","@id":"https:\/\/pfc.parts\/webcat\/#website","url":"https:\/\/pfc.parts\/webcat\/","name":"PFC Brakes applications","description":"PFC Brakes - Performance Friction","publisher":{"@id":"https:\/\/pfc.parts\/webcat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pfc.parts\/webcat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pfc.parts\/webcat\/#organization","name":"PFC Brakes","url":"https:\/\/pfc.parts\/webcat\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pfc.parts\/webcat\/#\/schema\/logo\/image\/","url":"https:\/\/pfc.parts\/webcat\/wp-content\/uploads\/2022\/01\/BMW-RACE-DISC-CALIPER-sm.png","contentUrl":"https:\/\/pfc.parts\/webcat\/wp-content\/uploads\/2022\/01\/BMW-RACE-DISC-CALIPER-sm.png","width":400,"height":327,"caption":"PFC Brakes"},"image":{"@id":"https:\/\/pfc.parts\/webcat\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PFCBrakes","https:\/\/x.com\/PFCbrakes","https:\/\/www.instagram.com\/pfcbrakes\/"]}]}},"_links":{"self":[{"href":"https:\/\/pfc.parts\/webcat\/wp-json\/wp\/v2\/product_cat\/88","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pfc.parts\/webcat\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/pfc.parts\/webcat\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/pfc.parts\/webcat\/wp-json\/wp\/v2\/product?product_cat=88"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}